{"id":39,"count":6,"description":"","link":"https:\/\/fim-medical.com\/en\/category\/faq-en\/vision-en\/","name":"Vision","slug":"vision-en","taxonomy":"category","parent":38,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Vision &#8226; FIM MEDICAL PROD<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fim-medical.com\/en\/category\/faq-en\/vision-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Vision &#8226; FIM MEDICAL PROD\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fim-medical.com\/en\/category\/faq-en\/vision-en\/\" \/>\n<meta property=\"og:site_name\" content=\"FIM MEDICAL PROD\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/category\\\/faq-en\\\/vision-en\\\/\",\"url\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/category\\\/faq-en\\\/vision-en\\\/\",\"name\":\"Archives des Vision &#8226; FIM MEDICAL PROD\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/category\\\/faq-en\\\/vision-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/category\\\/faq-en\\\/vision-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQ\",\"item\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/category\\\/faq-en\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vision\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/\",\"name\":\"FIM MEDICAL PROD\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/#organization\",\"name\":\"FIM Medical\",\"url\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/fim-medical.com\\\/wp-content\\\/uploads\\\/LOGO-FIM-MEDICAL-2.svg\",\"contentUrl\":\"https:\\\/\\\/fim-medical.com\\\/wp-content\\\/uploads\\\/LOGO-FIM-MEDICAL-2.svg\",\"width\":311,\"height\":136,\"caption\":\"FIM Medical\"},\"image\":{\"@id\":\"https:\\\/\\\/fim-medical.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Vision &#8226; FIM MEDICAL PROD","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fim-medical.com\/en\/category\/faq-en\/vision-en\/","og_locale":"en_US","og_type":"article","og_title":"Archives des Vision &#8226; FIM MEDICAL PROD","og_url":"https:\/\/fim-medical.com\/en\/category\/faq-en\/vision-en\/","og_site_name":"FIM MEDICAL PROD","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fim-medical.com\/en\/category\/faq-en\/vision-en\/","url":"https:\/\/fim-medical.com\/en\/category\/faq-en\/vision-en\/","name":"Archives des Vision &#8226; FIM MEDICAL PROD","isPartOf":{"@id":"https:\/\/fim-medical.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/fim-medical.com\/en\/category\/faq-en\/vision-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/fim-medical.com\/en\/category\/faq-en\/vision-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/fim-medical.com\/en\/"},{"@type":"ListItem","position":2,"name":"FAQ","item":"https:\/\/fim-medical.com\/en\/category\/faq-en\/"},{"@type":"ListItem","position":3,"name":"Vision"}]},{"@type":"WebSite","@id":"https:\/\/fim-medical.com\/en\/#website","url":"https:\/\/fim-medical.com\/en\/","name":"FIM MEDICAL PROD","description":"","publisher":{"@id":"https:\/\/fim-medical.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fim-medical.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/fim-medical.com\/en\/#organization","name":"FIM Medical","url":"https:\/\/fim-medical.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/fim-medical.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/fim-medical.com\/wp-content\/uploads\/LOGO-FIM-MEDICAL-2.svg","contentUrl":"https:\/\/fim-medical.com\/wp-content\/uploads\/LOGO-FIM-MEDICAL-2.svg","width":311,"height":136,"caption":"FIM Medical"},"image":{"@id":"https:\/\/fim-medical.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fim-medical.com\/en\/wp-json\/wp\/v2\/categories\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fim-medical.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/fim-medical.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/fim-medical.com\/en\/wp-json\/wp\/v2\/categories\/38"}],"wp:post_type":[{"href":"https:\/\/fim-medical.com\/en\/wp-json\/wp\/v2\/posts?categories=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}